{"id":20160,"date":"2022-02-03T17:23:53","date_gmt":"2022-02-03T16:23:53","guid":{"rendered":"https:\/\/kulibri.com\/?p=20160"},"modified":"2025-10-28T07:48:25","modified_gmt":"2025-10-28T06:48:25","slug":"ueber-uns","status":"publish","type":"post","link":"https:\/\/kulibri.com\/de\/ueber-uns","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"<p>Die Geschichte von kulibri beginnt Mitte der 1990er. Vier Jungs lernen sich beim Studium an der Uni Regensburg kennen (3x BWL, 1x Jura). Um den Kontakt zueinander nach dem Examen nicht zu verlieren, werden j\u00e4hrliche \u201eBuddy-Trips\u201c in verschiedene europ\u00e4ische St\u00e4dte unternommen. Bei der Organisation entstehen die nervigen E-Mail-Lawinen schon bei der Terminfindung, dann wieder bei der Auswahl des Zielortes und im Nachgang bei der Abrechnung der Ausgaben f\u00fcr Hotel, Fl\u00fcge, Mietwagen etc.<\/p>\n<p>Ab dem dritten \u201eBuddy-Trip\u201c werden die ersten selbst programmierten Tools eingesetzt, um online einsehbare Tabellen zu bef\u00fcllen. \u201eWer kann wann?\u201c oder \u201eWohin?\u201c werden die Programme genannt. Ein oder zwei Trips sp\u00e4ter kommt auch noch \u201ewer zahlt an wen?\u201c dazu und es werden bereits Anfragen aus dem Freundeskreis gestellt, ob man diese Programme auch mal benutzen d\u00fcrfte.<\/p>\n<p>Die erste kulibri Version geht 2006 online. Kulibri bleibt aber erstmal ein \u201epet project\u201c \u2013\u00a0 kostenlos und nat\u00fcrlich ohne Werbung. Die Gr\u00fcnder arbeiten nur sporadisch in der Freizeit ein wenig an kulibri.<\/p>\n<p>Kulibri w\u00e4chst die folgenden Jahre moderat oder gar nicht.<\/p>\n<p>Im Jahr 2019 vervielfacht sich die Anzahl der User aus aller Welt durch virale Effekte. Fast t\u00e4glich kommen Emails mit Danksagungen und Lob von den Usern an.<\/p>\n<p>Im Jahr 2021 wird der Entschluss gefasst, kulibri technologisch auf die n\u00e4chste Ebene zu heben und die User Experience zu verbessern.<\/p>\n<p>Das Entwicklungsteam wird verst\u00e4rkt, 2 Gr\u00fcnder widmen sich voll der neuen Herausforderung. kulibri bekommt ein neues Gesicht, eine komplett neue Bearbeitungsoberfl\u00e4che, individuelle Hintergrundbilder f\u00fcr Projekte und etliche weitere Funktionen, die sich die Benutzer \u00fcber die Jahre hinweg gew\u00fcnscht haben.<\/p>\n<p>Im Februar 2022 ist &#8220;Relaunch&#8221;. <strong>kulibri bleibt werbefrei, s\u00e4mtliche Daten liegen auf Servern in Deutschland und werden nicht an Dritte weiter gegeben.<\/strong><\/p>\n<p>Die neue Anwendung ist anfangs noch nicht perfekt, kommt aber sowohl bei bestehenden als auch bei neuen Usern und Userinnen sehr gut an und wird st\u00e4ndig verbessert.<br \/>Im Oktober 2022 werden die ersten Premium Funktionen angeboten.<\/p>\n<p>Dank sehr vielen und sehr treuen kulibri Fans und durch st\u00e4ndiges Zuh\u00f6ren w\u00e4chst kulibri in fast allen Kernzahlen im ersten Jahr nach Relaunch um mehr als 1000%.<\/p>\n<p>Stay tuned \ud83d\ude09<\/p>\n<p>Andreas, Alex, Mark<strong><br \/><\/strong><\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Geschichte von kulibri beginnt Mitte der 1990er. Vier Jungs lernen sich beim Studium an der Uni Regensburg kennen (3x BWL, 1x Jura). Um den Kontakt zueinander nach dem Examen nicht zu verlieren, werden j\u00e4hrliche \u201eBuddy-Trips\u201c in verschiedene europ\u00e4ische St\u00e4dte unternommen. Bei der Organisation entstehen die nervigen E-Mail-Lawinen schon bei der Terminfindung, dann wieder bei&hellip;<\/p>\n","protected":false},"author":15,"featured_media":19802,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[129],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.2.1 (Yoast SEO v18.4.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>kulibri &bull; \u00dcber uns<\/title>\n<meta name=\"description\" content=\"Eine kurze Beschreibung wo wir herkommen und was uns antreibt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kulibri.com\/de\/ueber-uns\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcber uns\" \/>\n<meta property=\"og:description\" content=\"Eine kurze Beschreibung wo wir herkommen und was uns antreibt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kulibri.com\/de\/ueber-uns\" \/>\n<meta property=\"og:site_name\" content=\"new kulibri\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-03T16:23:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T06:48:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kulibri.com\/wp-content\/uploads\/2022\/01\/test-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"30\" \/>\n\t<meta property=\"og:image:height\" content=\"30\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Kutzer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/kulibri.com\/de\/#organization\",\"name\":\"kulibri\",\"url\":\"https:\/\/kulibri.com\/de\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/kulibri.com\/de\/#logo\",\"inLanguage\":\"de\",\"url\":\"https:\/\/kulibri.com\/wp-content\/uploads\/2021\/10\/Kulibri_logo_v01_s-13.png\",\"contentUrl\":\"https:\/\/kulibri.com\/wp-content\/uploads\/2021\/10\/Kulibri_logo_v01_s-13.png\",\"width\":313,\"height\":92,\"caption\":\"kulibri\"},\"image\":{\"@id\":\"https:\/\/kulibri.com\/de\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kulibri.com\/de\/#website\",\"url\":\"https:\/\/kulibri.com\/de\/\",\"name\":\"new kulibri\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/kulibri.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kulibri.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/kulibri.com\/de\/ueber-uns#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/kulibri.com\/wp-content\/uploads\/2022\/01\/test-1.png\",\"contentUrl\":\"https:\/\/kulibri.com\/wp-content\/uploads\/2022\/01\/test-1.png\",\"width\":30,\"height\":30,\"caption\":\"Termin finden\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kulibri.com\/de\/ueber-uns#webpage\",\"url\":\"https:\/\/kulibri.com\/de\/ueber-uns\",\"name\":\"kulibri &bull; \u00dcber uns\",\"isPartOf\":{\"@id\":\"https:\/\/kulibri.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kulibri.com\/de\/ueber-uns#primaryimage\"},\"datePublished\":\"2022-02-03T16:23:53+00:00\",\"dateModified\":\"2025-10-28T06:48:25+00:00\",\"description\":\"Eine kurze Beschreibung wo wir herkommen und was uns antreibt.\",\"breadcrumb\":{\"@id\":\"https:\/\/kulibri.com\/de\/ueber-uns#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kulibri.com\/de\/ueber-uns\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kulibri.com\/de\/ueber-uns#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/kulibri.com\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber uns\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/kulibri.com\/de\/ueber-uns#article\",\"isPartOf\":{\"@id\":\"https:\/\/kulibri.com\/de\/ueber-uns#webpage\"},\"author\":{\"@id\":\"https:\/\/kulibri.com\/de\/#\/schema\/person\/acae8c506cbf7bba565712470e43d0dd\"},\"headline\":\"\u00dcber uns\",\"datePublished\":\"2022-02-03T16:23:53+00:00\",\"dateModified\":\"2025-10-28T06:48:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kulibri.com\/de\/ueber-uns#webpage\"},\"wordCount\":364,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kulibri.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/kulibri.com\/de\/ueber-uns#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kulibri.com\/wp-content\/uploads\/2022\/01\/test-1.png\",\"articleSection\":[\"Firma\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kulibri.com\/de\/ueber-uns#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kulibri.com\/de\/#\/schema\/person\/acae8c506cbf7bba565712470e43d0dd\",\"name\":\"Andreas Kutzer\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/kulibri.com\/de\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a8bae6957fd8b8dd0aee0f6316a1b0ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a8bae6957fd8b8dd0aee0f6316a1b0ab?s=96&d=mm&r=g\",\"caption\":\"Andreas Kutzer\"},\"url\":\"https:\/\/kulibri.com\/de\/author\/new_admin_2025\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"kulibri &bull; \u00dcber uns","description":"Eine kurze Beschreibung wo wir herkommen und was uns antreibt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kulibri.com\/de\/ueber-uns","og_locale":"de_DE","og_type":"article","og_title":"\u00dcber uns","og_description":"Eine kurze Beschreibung wo wir herkommen und was uns antreibt.","og_url":"https:\/\/kulibri.com\/de\/ueber-uns","og_site_name":"new kulibri","article_published_time":"2022-02-03T16:23:53+00:00","article_modified_time":"2025-10-28T06:48:25+00:00","og_image":[{"width":30,"height":30,"url":"https:\/\/kulibri.com\/wp-content\/uploads\/2022\/01\/test-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andreas Kutzer","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/kulibri.com\/de\/#organization","name":"kulibri","url":"https:\/\/kulibri.com\/de\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/kulibri.com\/de\/#logo","inLanguage":"de","url":"https:\/\/kulibri.com\/wp-content\/uploads\/2021\/10\/Kulibri_logo_v01_s-13.png","contentUrl":"https:\/\/kulibri.com\/wp-content\/uploads\/2021\/10\/Kulibri_logo_v01_s-13.png","width":313,"height":92,"caption":"kulibri"},"image":{"@id":"https:\/\/kulibri.com\/de\/#logo"}},{"@type":"WebSite","@id":"https:\/\/kulibri.com\/de\/#website","url":"https:\/\/kulibri.com\/de\/","name":"new kulibri","description":"","publisher":{"@id":"https:\/\/kulibri.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kulibri.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"https:\/\/kulibri.com\/de\/ueber-uns#primaryimage","inLanguage":"de","url":"https:\/\/kulibri.com\/wp-content\/uploads\/2022\/01\/test-1.png","contentUrl":"https:\/\/kulibri.com\/wp-content\/uploads\/2022\/01\/test-1.png","width":30,"height":30,"caption":"Termin finden"},{"@type":"WebPage","@id":"https:\/\/kulibri.com\/de\/ueber-uns#webpage","url":"https:\/\/kulibri.com\/de\/ueber-uns","name":"kulibri &bull; \u00dcber uns","isPartOf":{"@id":"https:\/\/kulibri.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kulibri.com\/de\/ueber-uns#primaryimage"},"datePublished":"2022-02-03T16:23:53+00:00","dateModified":"2025-10-28T06:48:25+00:00","description":"Eine kurze Beschreibung wo wir herkommen und was uns antreibt.","breadcrumb":{"@id":"https:\/\/kulibri.com\/de\/ueber-uns#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kulibri.com\/de\/ueber-uns"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kulibri.com\/de\/ueber-uns#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kulibri.com\/de"},{"@type":"ListItem","position":2,"name":"\u00dcber uns"}]},{"@type":"Article","@id":"https:\/\/kulibri.com\/de\/ueber-uns#article","isPartOf":{"@id":"https:\/\/kulibri.com\/de\/ueber-uns#webpage"},"author":{"@id":"https:\/\/kulibri.com\/de\/#\/schema\/person\/acae8c506cbf7bba565712470e43d0dd"},"headline":"\u00dcber uns","datePublished":"2022-02-03T16:23:53+00:00","dateModified":"2025-10-28T06:48:25+00:00","mainEntityOfPage":{"@id":"https:\/\/kulibri.com\/de\/ueber-uns#webpage"},"wordCount":364,"commentCount":0,"publisher":{"@id":"https:\/\/kulibri.com\/de\/#organization"},"image":{"@id":"https:\/\/kulibri.com\/de\/ueber-uns#primaryimage"},"thumbnailUrl":"https:\/\/kulibri.com\/wp-content\/uploads\/2022\/01\/test-1.png","articleSection":["Firma"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kulibri.com\/de\/ueber-uns#respond"]}]},{"@type":"Person","@id":"https:\/\/kulibri.com\/de\/#\/schema\/person\/acae8c506cbf7bba565712470e43d0dd","name":"Andreas Kutzer","image":{"@type":"ImageObject","@id":"https:\/\/kulibri.com\/de\/#personlogo","inLanguage":"de","url":"https:\/\/secure.gravatar.com\/avatar\/a8bae6957fd8b8dd0aee0f6316a1b0ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8bae6957fd8b8dd0aee0f6316a1b0ab?s=96&d=mm&r=g","caption":"Andreas Kutzer"},"url":"https:\/\/kulibri.com\/de\/author\/new_admin_2025"}]}},"jetpack_featured_media_url":"https:\/\/kulibri.com\/wp-content\/uploads\/2022\/01\/test-1.png","_links":{"self":[{"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/posts\/20160"}],"collection":[{"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/comments?post=20160"}],"version-history":[{"count":3,"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/posts\/20160\/revisions"}],"predecessor-version":[{"id":21887,"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/posts\/20160\/revisions\/21887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/media\/19802"}],"wp:attachment":[{"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/media?parent=20160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/categories?post=20160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kulibri.com\/de\/wp-json\/wp\/v2\/tags?post=20160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}